{"id":336,"date":"2023-12-27T20:19:44","date_gmt":"2023-12-27T19:19:44","guid":{"rendered":"https:\/\/bumerania.com\/noticias\/index.php\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/"},"modified":"2024-10-31T11:19:57","modified_gmt":"2024-10-31T10:19:57","slug":"bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante","status":"publish","type":"post","link":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/","title":{"rendered":"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante"},"content":{"rendered":"<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/<br \/>\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua1-1024x768.jpg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua1-1024x768.jpg 1024w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua1-300x225.jpg 300w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua1-768x576.jpg 768w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua1.jpg 1080w\" alt=\"\" width=\"800\" height=\"600\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua2-1024x768.jpg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua2-1024x768.jpg 1024w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua2-300x225.jpg 300w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua2-768x576.jpg 768w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua2.jpg 1080w\" alt=\"\" width=\"800\" height=\"600\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua3-1024x768.jpg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua3-1024x768.jpg 1024w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua3-300x225.jpg 300w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua3-768x576.jpg 768w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua3-1536x1151.jpg 1536w, https:\/\/bumerania.com\/wp-content\/uploads\/2023\/12\/ua3.jpg 2048w\" alt=\"\" width=\"800\" height=\"600\" \/><\/p>\n<p><main id=\"contenido-pagina\"><\/main><\/p>\n<section data-type=\"container\" data-name=\"cols-1\">\n<section data-type=\"component-tiny-text-ua\">Alicante, 22 de diciembre de 2023. El sal\u00f3n de actos de la Facultad de Educaci\u00f3n de la Universidad de Alicante (UA) acogi\u00f3 anoche el evento de cierre de la sexta edici\u00f3n del programa Gennera. Organizado por el Centro de Empleo de la UA, en colaboraci\u00f3n con el Parque Cient\u00edfico de Alicante (PCA), el programa Gennera busca crear un espacio de innovaci\u00f3n estrat\u00e9gica entre empresas referentes y estudiantes y egresados de la UA.<\/p>\n<p>Treinta estudiantes seleccionados de entre los m\u00e1s de cien inscritos fueron los encargados de presentar soluciones a los retos que plantearon las cinco empresas participantes. Estas soluciones se han generado tras tres meses de intenso trabajo, en los que se han celebrado once sesiones de trabajo, varias conversaciones con distintos expertos para aumentar la\u00a0visi\u00f3n sobre los procesos de\u00a0innovaci\u00f3n en las empresas y tres encuentros entre empresas\u00a0y equipos de trabajo.<\/p>\n<p>La jornada arranc\u00f3 con la bienvenida institucional a cargo de Esteban Pelayo, gerente del PCA y Sergi Soriano, director del Secretariado de Empleo y Apoyo a Estudiantes de la UA. En su intervenci\u00f3n, Soriano se\u00f1al\u00f3 que \u201csolo participar en este tipo de iniciativas que organiza el Centro de Empleo de la UA ya os coloca en ventaja con los compa\u00f1eros que no lo hacen, porque os dota de una serie de herramientas y habilidades que os ser\u00e1n de mucha utilidad en vuestra incorporaci\u00f3n al mercado laboral\u201d.<\/p>\n<p>El jurado de la sexta edici\u00f3n otorg\u00f3 la mayor puntuaci\u00f3n a la empresa de rob\u00f3tica social, vinculada al PCA,\u00a0<strong>Bumerania<\/strong>, que plante\u00f3 el reto de construir el hotel del futuro. Su equipo, como soluci\u00f3n, propuso una gran cartera de tecnolog\u00edas conectadas que ser\u00e1n capaces de adaptar los hoteles a las necesidades de todas las personas independientemente de que puedan tener cualquier tipo de discapacidad. Entre otras plantearon la instalaci\u00f3n de un avatar con IA que d\u00e9 la bienvenida a los clientes en su habitaci\u00f3n y que ser\u00e1 capaz de orientar y dar todo tipo de informaci\u00f3n. Distintos recursos para favorecer la movilidad dentro del hotel o dispositivos biom\u00e9tricos fueron otros de los avances propuestos en su soluci\u00f3n.<\/p>\n<p>El equipo\u00a0<strong>Accenture<\/strong>\u00a0present\u00f3 una soluci\u00f3n basada en una APP dotada con IA para ayudar a personas de edad avanzada a relacionarse con las nuevas tecnol\u00f3gicas. La llamaron \u201cIGA, la IA que te entiende\u201d.<\/p>\n<p>Por su parte, el equipo de la empresa\u00a0<strong>Aiudo<\/strong>\u00a0propuso una iniciativa que llam\u00f3 \u201cAida\u201d, un chat bot con un avatar capaz de aclarar todas las dudas de los nuevos clientes de la compa\u00f1\u00eda. Adem\u00e1s, propusieron el env\u00edo de un \u201cStarter Pack\u201d con informaci\u00f3n no digital a todos los nuevos usuarios de sus servicios.<\/p>\n<p>Los participantes del equipo adscrito a la empresa\u00a0<strong>Benigar<\/strong>\u00a0propusieron la creaci\u00f3n de espacios de venta innovadores, a los que llamaron \u201cBenibreathe\u201d. Estos espacios, que estar\u00e1n dotados con la \u00faltima tecnolog\u00eda dispondr\u00e1n de cafeter\u00eda, puntos de carga para patinetes el\u00e9ctricos, etc., y se convertir\u00e1n en referentes de la nueva realidad de la micromovilidad. Adem\u00e1s, plantearon una completa campa\u00f1a de marketing con sorteos, contrataci\u00f3n de influencers, conciertos, etc.<\/p>\n<p>La empresa tecnol\u00f3gica\u00a0<strong>Facephi<\/strong>\u00a0propuso como reto a los estudiantes la generaci\u00f3n de iniciativas que les ayudara a captar talento tecnol\u00f3gico. Como soluci\u00f3n, los estudiantes plantearon la creaci\u00f3n de \u201cPhiclub\u201d, una agrupaci\u00f3n que ofrezca a sus miembros distintas actividades como un \u201cescapebox\u201d en determinados eventos, colaboraciones estrat\u00e9gicas con influencers del sector, \u201cFacephi Talks\u201d como herramientas para conocer y hablar con expertos de temas de inter\u00e9s, workshops, eventos y competiciones tecnol\u00f3gicas.<\/p>\n<p>Gennera forma parte del programa \u201cCampus del Emprendimiento Innovador\u201d que se desarrolla en conjunto entre las cinco universidades p\u00fablicas valencianas, y\u00a0 est\u00e1 coordinado y financiado por la Conselleria de Innovaci\u00f3n, Industria, Comercio y Turismo de la Generalitat Valenciana con el objetivo de impulsar el emprendimiento y la innovaci\u00f3n en el \u00e1mbito universitario.<\/p>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Alicante, 22 de diciembre de 2023. El sal\u00f3n de actos de la Facultad de Educaci\u00f3n de la Universidad de Alicante (UA) acogi\u00f3 anoche el evento de cierre de la sexta edici\u00f3n del programa Gennera. Organizado por el Centro de Empleo de la UA, en colaboraci\u00f3n con el Parque Cient\u00edfico de Alicante (PCA), el programa Gennera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":337,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[31],"tags":[],"class_list":["post-336","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.4 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante - Bumerania | Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante\" \/>\n<meta property=\"og:description\" content=\"Alicante, 22 de diciembre de 2023. El sal\u00f3n de actos de la Facultad de Educaci\u00f3n de la Universidad de Alicante (UA) acogi\u00f3 anoche el evento de cierre de la sexta edici\u00f3n del programa Gennera. Organizado por el Centro de Empleo de la UA, en colaboraci\u00f3n con el Parque Cient\u00edfico de Alicante (PCA), el programa Gennera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/\" \/>\n<meta property=\"og:site_name\" content=\"Bumerania | Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-27T19:19:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T10:19:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bumerania.com\/noticias\/wp-content\/uploads\/2024\/10\/ua2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hector\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hector\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/\"},\"author\":{\"name\":\"hector\",\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/#\\\/schema\\\/person\\\/3fd52764a1c56194569c198775ca68dc\"},\"headline\":\"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante\",\"datePublished\":\"2023-12-27T19:19:44+00:00\",\"dateModified\":\"2024-10-31T10:19:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/\"},\"wordCount\":688,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/ua2.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/\",\"url\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/\",\"name\":\"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante - Bumerania | Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/ua2.jpg\",\"datePublished\":\"2023-12-27T19:19:44+00:00\",\"dateModified\":\"2024-10-31T10:19:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/#\\\/schema\\\/person\\\/3fd52764a1c56194569c198775ca68dc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/ua2.jpg\",\"contentUrl\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/ua2.jpg\",\"width\":1080,\"height\":810,\"caption\":\"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/2023\\\/12\\\/27\\\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/\",\"name\":\"Bumerania | Noticias\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/#\\\/schema\\\/person\\\/3fd52764a1c56194569c198775ca68dc\",\"name\":\"hector\",\"sameAs\":[\"https:\\\/\\\/bumerania.com\\\/noticias\"],\"url\":\"https:\\\/\\\/bumerania.com\\\/noticias\\\/author\\\/hector\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante - Bumerania | Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/","og_locale":"es_ES","og_type":"article","og_title":"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante","og_description":"Alicante, 22 de diciembre de 2023. El sal\u00f3n de actos de la Facultad de Educaci\u00f3n de la Universidad de Alicante (UA) acogi\u00f3 anoche el evento de cierre de la sexta edici\u00f3n del programa Gennera. Organizado por el Centro de Empleo de la UA, en colaboraci\u00f3n con el Parque Cient\u00edfico de Alicante (PCA), el programa Gennera [&hellip;]","og_url":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/","og_site_name":"Bumerania | Noticias","article_published_time":"2023-12-27T19:19:44+00:00","article_modified_time":"2024-10-31T10:19:57+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/bumerania.com\/noticias\/wp-content\/uploads\/2024\/10\/ua2.jpg","type":"image\/jpeg"}],"author":"hector","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hector","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/#article","isPartOf":{"@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/"},"author":{"name":"hector","@id":"https:\/\/bumerania.com\/noticias\/#\/schema\/person\/3fd52764a1c56194569c198775ca68dc"},"headline":"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante","datePublished":"2023-12-27T19:19:44+00:00","dateModified":"2024-10-31T10:19:57+00:00","mainEntityOfPage":{"@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/"},"wordCount":688,"commentCount":0,"image":{"@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/#primaryimage"},"thumbnailUrl":"https:\/\/bumerania.com\/noticias\/wp-content\/uploads\/2024\/10\/ua2.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/bumerania.com\/noticias\/#organization"}},{"@type":"WebPage","@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/","url":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/","name":"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante - Bumerania | Noticias","isPartOf":{"@id":"https:\/\/bumerania.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/#primaryimage"},"image":{"@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/#primaryimage"},"thumbnailUrl":"https:\/\/bumerania.com\/noticias\/wp-content\/uploads\/2024\/10\/ua2.jpg","datePublished":"2023-12-27T19:19:44+00:00","dateModified":"2024-10-31T10:19:57+00:00","author":{"@id":"https:\/\/bumerania.com\/noticias\/#\/schema\/person\/3fd52764a1c56194569c198775ca68dc"},"breadcrumb":{"@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/#primaryimage","url":"https:\/\/bumerania.com\/noticias\/wp-content\/uploads\/2024\/10\/ua2.jpg","contentUrl":"https:\/\/bumerania.com\/noticias\/wp-content\/uploads\/2024\/10\/ua2.jpg","width":1080,"height":810,"caption":"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante"},{"@type":"BreadcrumbList","@id":"https:\/\/bumerania.com\/noticias\/2023\/12\/27\/bumerania-gana-el-6a-edicion-del-gennera-de-la-universidad-de-alicante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bumerania.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Bumerania gana la 6\u00aa edici\u00f3n del Gennera de la Universidad de Alicante"}]},{"@type":"WebSite","@id":"https:\/\/bumerania.com\/noticias\/#website","url":"https:\/\/bumerania.com\/noticias\/","name":"Bumerania | Noticias","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bumerania.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/bumerania.com\/noticias\/#\/schema\/person\/3fd52764a1c56194569c198775ca68dc","name":"hector","sameAs":["https:\/\/bumerania.com\/noticias"],"url":"https:\/\/bumerania.com\/noticias\/author\/hector\/"}]}},"_links":{"self":[{"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/posts\/336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/comments?post=336"}],"version-history":[{"count":0,"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/posts\/336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/media\/337"}],"wp:attachment":[{"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/media?parent=336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/categories?post=336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bumerania.com\/noticias\/wp-json\/wp\/v2\/tags?post=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}